{"id":83,"date":"2014-05-27T15:09:39","date_gmt":"2014-05-27T14:09:39","guid":{"rendered":"http:\/\/tirra.net\/web\/?p=83"},"modified":"2014-08-17T15:10:41","modified_gmt":"2014-08-17T14:10:41","slug":"traduction-de-la-litterature-etrangere-vers-lamazighe-quel-projet-traductif-adopter","status":"publish","type":"post","link":"https:\/\/tirra.net\/web\/traduction-de-la-litterature-etrangere-vers-lamazighe-quel-projet-traductif-adopter\/","title":{"rendered":"Traduction de la litt\u00e9rature \u00e9trang\u00e8re vers l\u2019Amazighe. Quel projet traductif adopter ?"},"content":{"rendered":"<p style=\"text-align: right;\">\u00c9crit par Radi Mohammed.<\/p>\n<p style=\"text-align: right;\">Source: www.amazighnews.net<\/p>\n<p style=\"text-align: justify;\">La traduction a \u00e9t\u00e9, durant toute l&rsquo;histoire de la connaissance, un moyen de promotion des langues maternelles et de fondation de la litt\u00e9rature. C&rsquo;\u00e9tait \u00e9galement un outil de d\u00e9veloppement des cultures et d&rsquo;ouverture sur l&rsquo;universel. Le mouvement de traduction arabe encadr\u00e9 par l&rsquo;\u00e9tat au 3\u00e8me si\u00e8cle de l&rsquo;H\u00e9gire, a construit la litt\u00e9rature arabe, il a d\u00e9diactilis\u00e9 la langue pour faire d&rsquo;elle une langue commune. Au 19\u00e8me si\u00e8cle, la traduction de la litt\u00e9rature anglo-saxonne a transform\u00e9 la langue allemande en une langue litt\u00e9raire \u00e9crite. L&rsquo;acte traductif \u00e9tait donc li\u00e9 aux civilisations et \u00e0 la litt\u00e9rature.<!--more--><\/p>\n<p style=\"text-align: justify;\">La langue et la culture amazighes ne peuvent donc faire exeption \u00e0 cette r\u00e9gle. Une traduction institutionnelle dans le cadre d&rsquo;un projet, enrichera le lexique, am\u00e9liorera le style et cr\u00e9era de nouveaux sens au sein de la langue- culture.<\/p>\n<p style=\"text-align: justify;\">Mais quel projet traductif adopter pour atteindre ces objectifs ? Il n&rsquo;y a pas \u00ab\u00a0un mod\u00e8le \u00e0 suivre\u00a0\u00bb en traduction. La traduction varie selon les objectifs qui lui sont assign\u00e9s. On parle de versions abr\u00e9g\u00e9es, versions adapt\u00e9es et m\u00eame de multiples versions d&rsquo;une oeuvre dans une m\u00eame langue, comme les cas de Hom\u00e8re, Millle et une Nuits et La Bible) .<\/p>\n<p style=\"text-align: justify;\">De ce fait, pour traduire les oeuvres litt\u00e9raires vers l&rsquo;amazighe, il faut une strat\u00e9gie traduisante qui prendra en consid\u00e9ration le statut et la r\u00e9alit\u00e9 actuels de l&rsquo;amazighe, \u00e0 savoir: une graphie inaccessible \u00e0 tous les marocains, ce qui r\u00e9duit le lectorat potentiel, la communication des usagers de la langue avec trois variantes r\u00e9gionales, l&rsquo;existence d&rsquo;une terminologie qui puisait dans un environement rustique. En contrepartie, on poss\u00e8de un patrimoine litt\u00e9raire oral riche (po\u00e9sie, contes, mythes..) traduit vers d&rsquo;autres langues \u00e9trang\u00e8res notamment le fran\u00e7ais.<\/p>\n<p>Suite \u00e0 cet \u00e9tat des lieux, le projet traductif vers l&rsquo;amazighe peut \u00eatre d\u00e9fini par des r\u00e9ponses aux questions suivantes:<\/p>\n<p>Quels ouvrages choisir pour les transposer ou adapter \u00e0 l&rsquo;amazighit\u00e9 ?<\/p>\n<p>Le traduit, pour quel lectorat est-il destin\u00e9 ?<\/p>\n<p>Comment prendre une d\u00e9cision terminlogique devant cette inflation de n\u00e9ologismes ou de \u00a0\u00bb nouveaux-n\u00e9s linguistiques ?<\/p>\n<p>Quels proc\u00e9d\u00e9s traductifs appliquer \u00e0 l&rsquo;original pour adapter le texte cible \u00e0 la langue-culture amazighe ?<\/p>\n<p>Comment exploiter les trois variantes de Tamazight au cours de la r\u00e9expression du texte source ?<\/p>\n<h2>Le choix du texte source<\/h2>\n<p style=\"text-align: justify;\">Le choix du texte source est une \u00e9tape tr\u00e8s importante dans un projet traductif. Un mauvais choix condamnera la traduction \u00e0 l&rsquo;ecartement et aux archives. Et pour \u00e9viter une telle situation, la traduction en amazighe doit b\u00e9n\u00e9ficier des acquis des mouvements des traductions arabe, allemande et anglo-saxone. Ces mouvements ont ax\u00e9 leurs traductions au d\u00e9but, sur les \u00ab\u00a0grandes oeuvres\u00a0\u00bb, c&rsquo;est \u00e0 dire celles qui ont une meilleur reception, celles qui ont pass\u00e9 du national \u00e0 l&rsquo;univesel et qui ont subi au cours des si\u00e8cles des traductions dans presque toutes les langues.<\/p>\n<p style=\"text-align: justify;\">Dans la litt\u00e9rature arabe par exemple, on peut citer \u00a0\u00bb Les Milles et une Nuits, Kalila wa Dimna, le Saint Coran. Dans la litt\u00e9rature fran\u00e7aise, il ya Les Fables de Jean Fontaine, Le Petit Prince de Saint-Ex\u00e9pury, les M\u00e9sirables de Victor Hugo et les Contes de Charles Perrault. Dans la litt\u00e9rature Allemande, il ya les Contes des Fr\u00e8res Grim. Ces oeuvres subissent des traductions et des re-traductions m\u00eame \u00e0 notre siecle.<\/p>\n<p style=\"text-align: justify;\">Kalila wa Dimna, les Fables de La Fontaine, Les fr\u00e8res Grimm sont donc des oeuvres parmi d&rsquo;autres qui peuvent subir une transposition vers l&rsquo;amazighe parce que ce sont des discours litt\u00e9raires d&rsquo;ethique et de sagesse, s\u00e9culaires, universels et sans vocabulaire technique. Le premier est un discours prosaique qui v\u00e9hicule la culture indienne, perse et arabo-islamique, le second rel\u00e8ve du discours po\u00e9tique, son auteur s&rsquo;est inspir\u00e9 de la culture grecque, indienne et fran\u00e7aise. Le dernier regroupe le conte populaire allemand qu&rsquo;on peut comparer aux contes qui constituent la tradition orale amazighe.<\/p>\n<p style=\"text-align: justify;\">Rendre cette litt\u00e9rature dans la langue amazighe, c&rsquo;est s&rsquo;ouvrir sur l&rsquo;interculturali\u00e9 et garantir la lecture et l&rsquo;acceptabilit\u00e9 du traduit.<\/p>\n<h2>Le lectorat de Tamazight<\/h2>\n<p>Actuellement, il n&rsquo;y a pas une g\u00e9n\u00e9ration apparente qui maitrise la lecture et l&rsquo;\u00e9criture des textes en tifinagh, graph\u00e8mes officiels de Tamazighte. Ces graph\u00e8mes ne sont d\u00e9cod\u00e9s que par quelques adh\u00e9rants des associations militantes et quelques groupes de chercheurs qui s&rsquo;interessent \u00e0 l&rsquo;amazighit\u00e9. Aux \u00e9coles o\u00f9 on enseigne la langue amazighe, on a commenc\u00e9 \u00e0 apprendre les mots sans passer vraiment \u00e0 la lecture des textes.<\/p>\n<p>Le lecteur des manuels scolaires de Tamazighte trouve des dificult\u00e9s \u00e0 construire le sens parce que les termes qui constituent le lexique du texte sont soit des n\u00e9ologismes qui n\u00e9c\u00e9ssitent un dictionnaire pour les comprendre, soit des termes \u00e0 dominance de Tachlhit ou Tamazight ou Tarifit.<\/p>\n<p>Par cons\u00e9quent, pour assurer une meilleur r\u00e9ception du texte traduit, le traducteur doit r\u00e9diger son texte avec un style simple qui prendra en consid\u00e9ration ces dificult\u00e9s soulev\u00e9es.<\/p>\n<h2>La prise de d\u00e9cision terminologique<\/h2>\n<p style=\"text-align: justify;\">Il n&rsquo;est pas \u00e9vident de trancher sur l&rsquo;\u00e9quivalent d&rsquo;un terme dans un environnement verbal, c&rsquo;est \u00e0 dire prendre une d\u00e9cision terminologique. Je ne fais pas ici allusion aux probl\u00e8mes de la polys\u00e9mie mais \u00e0 l&rsquo;h\u00e9sitation du traducteur devant le choix d&rsquo;un terme emprunt\u00e9 ou d&rsquo;un archaisme ou d&rsquo;un n\u00e9ologisme attest\u00e9 ou \u00e0 tester.<\/p>\n<p style=\"text-align: justify;\">En effet, ces derni\u00e8res d\u00e9c\u00e9nnies, plusieurs personnes et institutions s&rsquo;interessent \u00e0 la n\u00e9ologie lexicale amazighe : les associations, les universit\u00e9s, les universitaires, les journalistes et les po\u00e9tes. Chacun essaye de forger ses \u00ab\u00a0designs terminologiques\u00a0\u00bb (mot emprunt\u00e9 \u00e0 Jean-Ren\u00e9 Ladmiral), tout en n\u00e9gligeant la dimension identitaire, culturel et communicative de Tamazighte. Le linguiste fouillent dans les racines de la langue pour cr\u00e9er ses \u00ab\u00a0nouveaux-n\u00e9s linguistiques\u00a0\u00bb. Le g\u00e9ologue et le math\u00e9maticien amazighes se hatent pour produire leurs n\u00e9ologismes hors contexte pour les publier. Le traducteur profane \u00e0 son tour, calque les vocables et transcode les structures \u00e9trang\u00e8res en se basant sur ces dictionnaires bilingues extra-institutionnels. Ce qui aboutit \u00e0 l&rsquo;\u00e9parpillement et une inflation lexicale qui affectent l&rsquo;identit\u00e9, bloquent la communication et entravent l&rsquo;apprentissage de Tamazight.<\/p>\n<p style=\"text-align: justify;\">De ce fait, en traduisant il n&rsquo;est pas facile de prendre une d\u00e9cision terminologique devant cette g\u00e9n\u00e9ration lexicale si on veut atteindre l&rsquo;objectif de la traduction, qui est la communication d&rsquo;un message \u00a0\u00bb La v\u00e9ritable traduction est un acte de communication[1]\u00a0\u00bb.<\/p>\n<p style=\"text-align: justify;\">Pour bien illustrer mon propos, observons cette liste de dualit\u00e9s de termes synonymes. Les premiers sont des termes connus chez les usagers de la langue mais ce sont presque des termes empreint\u00e9s \u00e0 l&rsquo;arabe. Les seconds sont des termes m\u00e9connus chez les usagers, ils sont tir\u00e9s soit du dictionnaire de Chafiq soit du CAL de l&rsquo;IRCAM .<\/p>\n<p>\u00a0\u00bb lxir \/tullught, axddam \/ askkiw; rrhmt \/ tamlla, ikmml \/ imda, laman\/ taflast, rrzq \/ tirgitt, yumn \/ ifls, ickka\/ yurda, a3daw \/ amagzar, a3skri \/ asrdas, nnf3\/ tanafut, ighdr \/ ighafs, aghddar\/ aknnad, indm\/ immukrz , iqrrb\/ yuds, rruh\/ iman, ddin\/ aggad, ljid\/ amaggar, l3alim \/ amussn&#8230;?<\/p>\n<p style=\"text-align: justify;\">Le traducteur se trouve devant un dilemme, dois-il opter pour le terme emprunt\u00e9 \u00e0 l&rsquo;arabe et familer chez les usagers de la langue ou jouer le r\u00f4le du puriste et \u00e9carter l&#8217;emprunt en faisant confiance aux propositions des dictionnaires bilingues. \u00a0\u00bb Les dictionnaires bilingues qu&rsquo;on appelle abusivement (dictionnaires de traduction), ces ouvrages utiles renseignent sur les \u00e9quivalents correspondants aux acceptions les plus usuelles des unit\u00e9s lexicales de deux langues, mais ils sont loin d&rsquo;\u00e9puiser les possibilit\u00e9s s\u00e9mantiques des mots en contexte.[2]\u00a0\u00bb.<\/p>\n<p style=\"text-align: justify;\">Avant de trancher sur ce point, il faut situer la traduction vers l&rsquo;amazighe. Le lectorat cibl\u00e9 est l&rsquo;apprenant de l&rsquo;amazighe, l&rsquo;objectif de la traduction \u00e0 l&rsquo;\u00e9tat actuelle est de difuser tifinagh et les nouvelles r\u00e9gles orthographiques et grammaticales \u00e9tablies par l&rsquo;IRCAM. Il faut \u00e9galement promouvoir la langue amazighe, cr\u00e9er un nouveau registre et communiquer quelques valeurs humaines, religieuses et universelles pour enrichir la culture.<\/p>\n<p style=\"text-align: justify;\">Il parait donc que la traduction en amazighe doit \u00eatre \u00e0 cheval entre une traduction didactique et une une traduction interpr\u00e9tative, c&rsquo;est \u00e0 dire une traduction qui facilitera l&rsquo;apprentissage de la langue amazighe et en m\u00eame temps une traduction qui communiquera un message et des valeurs universelles.<\/p>\n<p style=\"text-align: justify;\">Ces objectifs imposent un texte traduit sans ambiguit\u00e9 lexicale ni s\u00e9mantique. Mais \u00e9galement un texte o\u00f9 on doit injecter progressivement des n\u00e9ologismes tout en faisant attention aux \u00ab\u00a0doses mortelles.<\/p>\n<p style=\"text-align: justify;\">Mais une traduction lisible, acceptable et claire est une version o\u00f9 le traducteur ignore les dictionnaires bilingues en faisant seulement appel \u00e0 la connaissance son dialecte. C&rsquo;est un texte \u00e0 unit\u00e9s discursives longues, on y proc\u00e8de \u00e0 l&rsquo;amputation des structures o\u00f9 un terme n&rsquo;a pas d&rsquo;\u00e9quivalent dans le dialecte, ce qui aboutit \u00e0 un puzzle. On r\u00e9duit le lectorat potentiel puisque seuls les amazighes de l&rsquo;une des trois r\u00e9gions qui peuvent lire la traduction. Au sein du texte, on remarquera un lexique o\u00f9 l&#8217;emprunt \u00e0 l&rsquo;arabe l&#8217;emporte sur le terme amazighe.<\/p>\n<p style=\"text-align: justify;\">Aors qu&rsquo;une une version avec un style litt\u00e9raire o\u00f9 les tous les sens sont transpos\u00e9s, le traducteur doit consulter les dictionnaires bilingues ( Chafiq, Taifi, Hddacchi&#8230;) pour purifier le texte de l&#8217;emprunt. On y remarquera l&rsquo;abondance de n\u00e9ologismes et une langue o\u00f9 on sent la traduction. Le lecteur trouvera des difficult\u00e9s \u00e0 d\u00e9coder le sens des phrases.<\/p>\n<p style=\"text-align: justify;\">Pour r\u00e9soudre ce probl\u00e8me, le traducteur doit prendre la d\u00e9cision terminologique selon les zones texuels traduites. Si dans une structure par exemple, le traducteur juge que le message v\u00e9hicul\u00e9 est fort au niveau culturel, et pour \u00e9viter toute ambiguit\u00e9 chez le lecteur sachant que celui-ci est peu initi\u00e9, il dois utiliser, sans complexe, lxir au lieu de tullught, a3daw au lieu de amagzar, indm au lieu de immukrz . Et Si dans d&rsquo;autres contextes, le traducteur voit que l&rsquo;ins\u00e9rertion d&rsquo;un n\u00e9ologisme n&rsquo;affectera pas le sens g\u00e9n\u00e9ral chez le lecteur, il peut tester (aggad, amagzar, imukrz&#8230;). Et c&rsquo;est cette audace d&rsquo;ailleurs des m\u00e9dias et des acteurs associatifs qui a fait fait de beaucoup de n\u00e9ologismes, des n\u00e9ologismes attest\u00e9s, comme (azul, tanmmirt, isnimmr, tamsmunt, tussna, asinag agldan, assgmi, anlmad, tinnml, taguri, adlis, assughl, taskla, (amuddu&#8230; Et on ne peut que f\u00e9liciter nos n\u00e9ologues de la r\u00e9ussite de ces termes.<\/p>\n<h2>Deux Proc\u00e9d\u00e9s Traductifs obligatoires :<\/h2>\n<h2>L&rsquo;excision et l&rsquo;expurgation<\/h2>\n<p style=\"text-align: justify;\">Pour illustrer ces deux proc\u00e9d\u00e9s, je prendrai comme exemple Kalila wa Dimna et les Fables de la Fontaine.<\/p>\n<p style=\"text-align: justify;\">Kalila wa Dimna, oeuvre de contes d&rsquo;animaux, a accumul\u00e9 une culture plurielle suite aux traductions s\u00e9culaires qu&rsquo;elle a subies, du sanscrit vers la langue persane et de celle-ci vers l&rsquo;arabe. Chaque traducteur, y introduit, de mani\u00e8re consciente ou inconsciente, sa culture, ses convictions et son environnement social et politique, c&rsquo;est dire sa subjectivi\u00e9.<\/p>\n<p style=\"text-align: justify;\">Ibnu Lmouqaffa, le traducteur de l&rsquo;ouvrage en question vers l&rsquo;arabe, a ins\u00e9r\u00e9 trois chapitres paratextules, qui sont tous \u00a0\u00bb des pr\u00e9faces allographes, tardives ou posthumes[3]\u00a0\u00bb c&rsquo;est \u00e0 dire des pr\u00e9faces des tiers apr\u00e8s le d\u00e9c\u00e8s de l&rsquo;auteur. Elles occupent presque un tiers de l&rsquo;espace du texte (58 pages sur 200). Ces pr\u00e9liminaires biographiques sur l&rsquo;auteur, les traducteurs, les Rois et les dirigeants politiques de l&rsquo;epoque (le Brahman Bidpay, Le Roi indien Dabchalim, le traducteur et m\u00e9decin Perse Bourzowih, le roi Perse Kisra Anouchirwan et son ministre Bouzourjomihr) se pr\u00e9sentent comme une partie du texte sous forme de contes, alors qu&rsquo;en r\u00e9alit\u00e9, il s&rsquo;agit d&rsquo;un discours \u00ab\u00a0hors-texte\u00a0\u00bb ou pratextuel qui pr\u00e9sente au lecteur un discours \u00e0 caract\u00e8re id\u00e9ologique. Faut-il transposer cette expansion vers l&rsquo;amazighe ou pr\u00e9senter une version nue sans paratexte ?<\/p>\n<p style=\"text-align: justify;\">Le travail du traducteur ne consiste pas uniquement en une transmission du message d&rsquo;une langue \u00e0 une autre, il doit d\u00e9tecter toutes les charges culturelles \u00e0 caract\u00e8re id\u00e9ologique qui constituent le discours \u00e0 traduire. Il doit avoir une comp\u00e9tence de s\u00e9lection des informations et proc\u00e9der \u00e0 l&rsquo;excision et l&rsquo;expurgation de celles qui contredisentt les valeurs de la langue-culture cible. Les pr\u00e9faces longues de Kalila wa Dimna s&rsquo;adressaient aux dirigeants politiques et aux Rois de l&rsquo;epoque alors que le texte amazighe cible l&rsquo;apprenant de Tamazight.<\/p>\n<p style=\"text-align: justify;\">Dans le texte des fables de La Fontaine \u00e9galement, il ya des Fables o\u00f9 l&rsquo;auteur s&rsquo;adresse \u00e0 une personne particuli\u00e8re comme Madame De La Sabli\u00e8re qui le prot\u00e9geait ou \u00e0 Madame Montespan ou \u00e0 un Duc de l&rsquo;epoque. Ces passages ne peuvent interesser notre lecteur actuel.<\/p>\n<p style=\"text-align: justify;\">Le traducteur n&rsquo;est donc pas oblig\u00e9 de traduire la totalit\u00e9 du corpus et toutes les composantes d&rsquo;un discours, il peut l&rsquo;abr\u00e9ger et proc\u00e9der au tri selon le lectorat, pour ne retenir que les \u00e9l\u00e9ments pertinents. \u00a0\u00bb Le proc\u00e9d\u00e9 r\u00e9ducteur le plus simple, mais aussi le plus brutal et le plus attentatoire \u00e0 sa structure et \u00e0 sa signification, consiste donc en une suppression pur et simple, ou excision&#8230;On peut \u00e9ventuellement am\u00e9liorer une oeuvre en supprimant chirurgicalement telle partie inutile et donc nuisible. [4]\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">L&rsquo;excision est une anticipation sur les pratiques du lecteur. Rares sont les lecteurs qui lisent toutes les composantes d&rsquo;une oeuvre, en g\u00e9n\u00e9ral ils proc\u00e8dent \u00e0 une lecture selective \u00ab\u00a0lire, c&rsquo;est bien \u00ab\u00a0ou mal\u00a0\u00bb choisir et choisir c&rsquo;est laisser[5]\u00a0\u00bb. Cette amputation peut etre li\u00e9e une autre pratique, l&rsquo;expurgation :<\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0L&rsquo;expurgation se marque non seulement par les suppressions, mais aussi des interventions destin\u00e9s \u00e0 expliquer des conduites choquantes ou suprenantes.[6]\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0versions expurge\u00e9s : c&rsquo;est une r\u00e9duction \u00e0 fonction moralisante ou \u00e9difiante. On y supprime pas seulement ce qui peut ennuyer le jeune lecteur ou ex\u00e9der ses facult\u00e9s intellectuelles, mais aussi ce qui peut \u00ab\u00a0troubler\u00a0\u00bb ou \u00ab\u00a0inqui\u00e9ter\u00a0\u00bb son innocence.[7]\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">Pour illustrer le proc\u00e9d\u00e9 d&rsquo;expurgation, il y a une fable de La Fontaine intitul\u00e9e : le Rat qui s&rsquo;est retir\u00e9 du monde. Il s&rsquo;agit d&rsquo;un Rat Croyant qui s&rsquo;est enrichi, mais avare. Il ferme la porte devant ses fr\u00e8res pauvres qui lui demandent l&rsquo;aum\u00f4ne et du secours. La morale du fabuliste nous apprend que ce Rat n&rsquo;est autre qu&rsquo;un musulman soufi (un dervis = derviche) et l&rsquo;auteur ajoute qu&rsquo;un moine ne peut pas faire ce geste parce qu&rsquo;il est charitable.<\/p>\n<h2>Extrait de la fable[8] :<\/h2>\n<p>Qui d\u00e9signais-je, \u00e0 votre avis,<\/p>\n<p>Par ce Rat si peu secourable ?<\/p>\n<p>Un moine ? Non, mais un dervis :<\/p>\n<p>Je suppose qu&rsquo;un moine est toujours charitable.<\/p>\n<p style=\"text-align: justify;\">Le traducteur doit utiliser son savoir-faire et son intuition pour adapter cette morale \u00e0 l&rsquo;environnement social et religieux du jeune lecteur. Il doit, soit l&rsquo;exciser totalement, soit l&rsquo;expurger pour d\u00e9vier sa charge affective. C&rsquo;est-\u00e0-dire annoncer que ce Rat est un moine et non un dervis et que ce dernier est toujours charitable.<\/p>\n<h2>Traduction propos\u00e9e<\/h2>\n<p>g rray nnun, magms ughrda a ?<\/p>\n<p>nna iruran s tadawt i ayt mas ?<\/p>\n<p>idd amhawch ? ihi, wa d arhbani<\/p>\n<p>amhawch, amaggar[9] ay d iya.<\/p>\n<h2>La r\u00e9expression<\/h2>\n<p style=\"text-align: justify;\">Nul ne peut nier l&rsquo;\u00e9cart entre la th\u00e9orie et la pratique de la traduction, mais il serait utile de citer de mani\u00e8re succincte les travaux de quelques traductologues et traducteurs. Le premier est Jean-Ren\u00e9 Ladmiral qui a forg\u00e9 deux n\u00e9ologismes : \u00ab\u00a0sourciers\u00a0\u00bb et \u00ab\u00a0ciblistes\u00a0\u00bb, selon qu&rsquo;on pr\u00e9viligie la langue source ou la langue cible lors de la reformulation de l&rsquo;original. Le second est Antoine Berman qui prend comme crit\u00e8res d&rsquo;\u00e9valuation d&rsquo;une traduction, l&rsquo;acceptabilit\u00e9 dans la langue r\u00e9ceptrice et la d\u00e9fectusit\u00e9 de quelques \u00a0\u00bb zones textuelles\u00a0\u00bb. Enfin, l&rsquo;approche des formateurs de ESIT en France (Ecole supp\u00e9rieure des Interpr\u00e8tes et Traducteurs) qui conseillent les futurs traducteurs de se documenter dans des textes parall\u00e8lles, oublier la texture de l&rsquo;original et r\u00e9exprimer le contenu avec une langue communicative.<\/p>\n<p style=\"text-align: justify;\">Donc, la r\u00e9expression du texte en amazighe doit investir, en plus des pratiques litt\u00e9raires cit\u00e9es, toutes ces donn\u00e9s des praticiens et traductologues.<\/p>\n<p style=\"text-align: justify;\">Autrement dit, apr\u00e8s avoir excis\u00e9, expurg\u00e9, pris la d\u00e9cision terminologique, d\u00e9termin\u00e9 les termes r\u00e9currents et quelques \u00ab\u00a0zones textuelles\u00a0\u00bb qui refl\u00e8tent le message de l&rsquo;original et ses aspects stylistiques, on peut reformuler le texte avec une langue communicative, fonctionnelle et acceptable chez l&rsquo;apprenant de Tamazighte.<\/p>\n<p style=\"text-align: justify;\">Pour le cas des contes de Kalila wa Dimna, voici quelques concepts r\u00e9currents qui refl\u00e8tent le vouloir-dire de l&rsquo;auteur et qui doivent figurer dans la r\u00e9expression du texte.<\/p>\n<p style=\"text-align: justify;\">l&rsquo;amiti\u00e9 (tiddukla), l&rsquo;amour (tayri), l&rsquo;alliance (tada), la fraternit\u00e9 (taymatt). \/ la sagesse (anzaz), l&rsquo;int\u00e9ligence (anngri, la science (tamussni), le savant (amussn), la recherche (asiggl), le devoir (tughunt), le travail (tawuri)\/. Gouverner (tanbadt), les rois (igllidn), le g\u00e9n\u00e9reux (amaggar, ljid), le pardon (asaruf), les ministres (imawasn), la dissension (amxalaf), l&rsquo;int\u00e9ret personnelle (tanafut nns), l&rsquo;hypocrisie (taxndllast), vil (amddallu)\/. Ici-bas (tudrt), Au-del\u00e0 (tamnadt inn), le licite (imzri), mystisme (tihiwcht), regret ( amukrz, nndamiyt), bonne action (lxir, tullught).\/ Le juge (anzzarfu), l&rsquo;accus\u00e9 (amnnurf), la preuve (anza), l&rsquo;avocat (anghlif), la libert\u00e9 (tidrfi, tilleli), faux temoignage (tuggi n zzur).\/se douter (yurda, ickka), traitre (aknnad, am3iwrt)), la femme (tamttut), la ruse (tidst), la mort ( lmut), le plaisir (ammizd)&#8230;<\/p>\n<h2>Conclusion<\/h2>\n<p style=\"text-align: justify;\">Un original universel bien choisi augmentera les chances de lecture de la traduction, de sa critique, de sa re-traduction et par cons\u00e9quent de sa r\u00e9ussite.<\/p>\n<p style=\"text-align: justify;\">Puisque l&rsquo;apprentissage de la langue est l&rsquo;un des objectifs de la traduction vers l&rsquo;amazighe, le texte cible doit respecter les nouvelles normes, doit \u00eatre concordant avec les publications de l&rsquo;IRCAM et en particulier les manuels scolaires pour \u00e9viter l&rsquo;\u00e9parpillement.<\/p>\n<p style=\"text-align: justify;\">Laprise de d\u00e9cision terminologique se base sur le choix des vocables qui \u00e9tablissent facilement la communication sans n\u00e9gliger ni abuser avec les n\u00e9ologie, ni se complexer de l&#8217;emprunt.<\/p>\n<p style=\"text-align: justify;\">Le tri ( l&rsquo;excision et l&rsquo;expurgation ) sont deux proc\u00e9d\u00e9s obligatoires dans l&rsquo;acte traductif pour adapter le texte au nouveau lectorat et son contexte social et politique.<\/p>\n<p style=\"text-align: left;\">Enfin, la traduction doit \u00ab\u00a0r\u00e9concilier \u00a0\u00bb ses trois dialectes. Si le traducteur est un locuteur natif de tamazight par exemple, il doit faire participer le lexique des deux autres dialectes par le biais d&rsquo;une recherche documentaire, pour aboutir une standardisation progressive de la langue.<\/p>\n<p style=\"text-align: left;\"><strong>Bibligraphie en Fran\u00e7ais<\/strong><\/p>\n<p>1) Genette.G, (1982) Pailmpseste, la litt\u00e9rature au second degr\u00e9, collection Po\u00e9tique, Editions du Seuil, Paris.<\/p>\n<p>2) Lavault.E (1985), Fonctions de traduction en didactique des langues, apprendre une langue en apprenant \u00e0 traduire, collection traductologie, N0 2, Didier Erudition.<\/p>\n<p>3) Genette.G (1987), Seuils, Collection Po\u00e9tique, Editions du Seuil, Paris.<\/p>\n<p>4) Durieux.C (1988), Fondement didactique de la traduction technique, Collection Trductologie, no 3, Didier Erudition,.<\/p>\n<p>5) Ladmiral.J, (1994); Traduire, Th\u00e9or\u00e8mes pour la traduction, Editions Gallimard, .<\/p>\n<p>6) Berman. A (1995), Pour une critique des traductions : John Donne, Editions Gallimard.<\/p>\n<p>7) La Fontaine. J (1996), Fables, Livres 7 \u00e0 12, Edition Marketing<\/p>\n<p>8) Saib. J et Al (2003), La place de la traduction dans le maintien d&rsquo;une langue, IRCAM, Rabat.<\/p>\n<p>9) IRCAM (CAL) (2006), Vocabulaire de la langue amazighe (Fran\u00e7ais- Amazighe) Rabat .<\/p>\n<p><strong>Bibliographie en Arabe<\/strong><\/p>\n<p>1) \u0645\u062d\u0645\u062f \u0634\u0641\u064a\u0642\u060c \u0627\u0644\u0645\u0639\u062c\u0645 \u0627\u0644\u0639\u0631\u0628\u064a &#8211; \u0627\u0644\u0623\u0645\u0627\u0632\u064a\u063a\u064a\u060c \u0623\u0643\u0627\u062f\u064a\u0645\u064a\u0629 \u0627\u0644\u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0645\u063a\u0631\u0628\u064a\u0629\u060c \u0633\u0644\u0633\u0644\u0629 \u0645\u0639\u0627\u062c\u0645\u060c\u0627\u0644\u062c\u0632\u0621 \u0627\u0644\u0623\u0648\u0644\u060c 1987 \u0648 \u0627\u0644\u062b\u0627\u0646\u064a 1989 \u0648 \u0627\u0644\u062b\u0627\u0644\u062b\u060c2000\u060c\u0627\u0644\u0631\u0628\u0627\u0637.<\/p>\n<p>2) \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0628\u0646 \u0627\u0644\u0645\u0642\u0641\u0639\u060c \u0643\u0644\u064a\u0644\u0629 \u0648 \u062f\u0645\u0646\u0629\u060c \u0627\u0644\u0645\u0643\u062a\u0628\u0629 \u0627\u0644\u0639\u0635\u0631\u064a\u0629 \u0628\u064a\u0631\u0648\u062a\u060c 2007.<\/p>\n<p>[1] Jean-Ren\u00e9 Ladmiral, traduire : th\u00e9or\u00e8mes pour la traduction, Gallimard,p 13.<\/p>\n<p>[2] Delisle Jean, L&rsquo;analyse du discours comme m\u00e9thode de traduction, Presses de l&rsquo;universit\u00e9 d&rsquo;Ottawa, 1980.<\/p>\n<p>[3] G\u00e9rard Genette, Seuil, collection Po\u00e9tique, Edition du Seuil, p 11.<\/p>\n<p>[4] G\u00e9rard Genette, Palimpsestes, Edition Seuil, p 264<\/p>\n<p>[5] Ibidem p 265<\/p>\n<p>[6] Ibidem p 290<\/p>\n<p>[7] Ibidem p 270<\/p>\n<p>[8] Recueil 2 Livre 7 fable 3<\/p>\n<p>[9] Amhawch = le soufi, amaggar = le charitable<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9crit par Radi Mohammed. Source: www.amazighnews.net La traduction a \u00e9t\u00e9, durant toute l&rsquo;histoire de la connaissance, un moyen de promotion des langues maternelles et de fondation de la litt\u00e9rature. C&rsquo;\u00e9tait \u00e9galement un outil de d\u00e9veloppement des cultures et d&rsquo;ouverture sur l&rsquo;universel. Le mouvement de traduction arabe encadr\u00e9 par l&rsquo;\u00e9tat au 3\u00e8me si\u00e8cle de l&rsquo;H\u00e9gire, a construit la litt\u00e9rature arabe, il a d\u00e9diactilis\u00e9 la langue pour faire d&rsquo;elle une langue commune. Au 19\u00e8me si\u00e8cle, la traduction de la litt\u00e9rature anglo-saxonne a transform\u00e9 la langue allemande en une langue litt\u00e9raire \u00e9crite. L&rsquo;acte traductif \u00e9tait donc li\u00e9 aux civilisations et \u00e0 la litt\u00e9rature.<\/p>\n","protected":false},"author":1,"featured_media":87,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[19,28],"tags":[],"class_list":["post-83","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nsti-awn-lus-pour-vous","category-tazrawt","entry","has-media"],"_links":{"self":[{"href":"https:\/\/tirra.net\/web\/wp-json\/wp\/v2\/posts\/83","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tirra.net\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tirra.net\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tirra.net\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tirra.net\/web\/wp-json\/wp\/v2\/comments?post=83"}],"version-history":[{"count":0,"href":"https:\/\/tirra.net\/web\/wp-json\/wp\/v2\/posts\/83\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tirra.net\/web\/wp-json\/wp\/v2\/media\/87"}],"wp:attachment":[{"href":"https:\/\/tirra.net\/web\/wp-json\/wp\/v2\/media?parent=83"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tirra.net\/web\/wp-json\/wp\/v2\/categories?post=83"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tirra.net\/web\/wp-json\/wp\/v2\/tags?post=83"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}